{"id":2486,"date":"2025-10-14T13:52:48","date_gmt":"2025-10-14T11:52:48","guid":{"rendered":"https:\/\/lebenshilfe-viernheim.de\/lhv\/?post_type=tribe_events&#038;p=2486"},"modified":"2025-10-14T13:52:48","modified_gmt":"2025-10-14T11:52:48","slug":"singstunde-im-johannes-schrey-haus-22","status":"publish","type":"tribe_events","link":"https:\/\/lebenshilfe-viernheim.de\/lhv\/event\/singstunde-im-johannes-schrey-haus-22\/","title":{"rendered":"Singstunde im Johannes Schrey Haus"},"content":{"rendered":"<div class=\"longdesc description\">\n<p><strong>Singstunde im Johannes Schrey Haus<\/strong><\/p>\n<p>Bewohner der Wohnst\u00e4tten Johannes-Schrey-Haus und der Schriesheimer Str. treffen sich im Mehrzweckraum um gemeinsam sch\u00f6ne, bekannte Lieder zu singen<\/p>\n<\/div>\n<div class=\"mc-location\">\n<div class=\"address location vcard\">\n<div class=\"adr h-card\">\n<div><strong class=\"location-link\">Johannes Schrey Haus Mehrzweckraum<\/strong><\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Singstunde im Johannes Schrey Haus Bewohner der Wohnst\u00e4tten Johannes-Schrey-Haus und der Schriesheimer Str. treffen sich im Mehrzweckraum um gemeinsam sch\u00f6ne, bekannte Lieder zu singen Johannes Schrey Haus Mehrzweckraum<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"jetpack_post_was_ever_published":false,"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":["post-2486","tribe_events","type-tribe_events","status-publish","hentry"],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/lebenshilfe-viernheim.de\/lhv\/wp-json\/wp\/v2\/tribe_events\/2486"}],"collection":[{"href":"https:\/\/lebenshilfe-viernheim.de\/lhv\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/lebenshilfe-viernheim.de\/lhv\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/lebenshilfe-viernheim.de\/lhv\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/lebenshilfe-viernheim.de\/lhv\/wp-json\/wp\/v2\/comments?post=2486"}],"version-history":[{"count":1,"href":"https:\/\/lebenshilfe-viernheim.de\/lhv\/wp-json\/wp\/v2\/tribe_events\/2486\/revisions"}],"predecessor-version":[{"id":2487,"href":"https:\/\/lebenshilfe-viernheim.de\/lhv\/wp-json\/wp\/v2\/tribe_events\/2486\/revisions\/2487"}],"wp:attachment":[{"href":"https:\/\/lebenshilfe-viernheim.de\/lhv\/wp-json\/wp\/v2\/media?parent=2486"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lebenshilfe-viernheim.de\/lhv\/wp-json\/wp\/v2\/tags?post=2486"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/lebenshilfe-viernheim.de\/lhv\/wp-json\/wp\/v2\/tribe_events_cat?post=2486"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}